{"id":573,"count":1,"description":"","link":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/","name":"scholarship for postgraduate students","slug":"scholarship-for-postgraduate-students","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>scholarship for postgraduate students Archives - UniRely<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"scholarship for postgraduate students Archives - UniRely\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/\" \/>\n<meta property=\"og:site_name\" content=\"UniRely\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/unirely.com\\\/blog\\\/tag\\\/scholarship-for-postgraduate-students\\\/\",\"url\":\"https:\\\/\\\/unirely.com\\\/blog\\\/tag\\\/scholarship-for-postgraduate-students\\\/\",\"name\":\"scholarship for postgraduate students Archives - UniRely\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unirely.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unirely.com\\\/blog\\\/tag\\\/scholarship-for-postgraduate-students\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unirely.com\\\/blog\\\/tag\\\/scholarship-for-postgraduate-students\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/unirely.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"scholarship for postgraduate students\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unirely.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/unirely.com\\\/blog\\\/\",\"name\":\"UniRely\",\"description\":\"College Counseling\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unirely.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"scholarship for postgraduate students Archives - UniRely","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/","og_locale":"en_US","og_type":"article","og_title":"scholarship for postgraduate students Archives - UniRely","og_url":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/","og_site_name":"UniRely","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/","url":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/","name":"scholarship for postgraduate students Archives - UniRely","isPartOf":{"@id":"https:\/\/unirely.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/unirely.com\/blog\/tag\/scholarship-for-postgraduate-students\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/unirely.com\/blog\/"},{"@type":"ListItem","position":2,"name":"scholarship for postgraduate students"}]},{"@type":"WebSite","@id":"https:\/\/unirely.com\/blog\/#website","url":"https:\/\/unirely.com\/blog\/","name":"UniRely","description":"College Counseling","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unirely.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/unirely.com\/blog\/wp-json\/wp\/v2\/tags\/573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unirely.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/unirely.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/unirely.com\/blog\/wp-json\/wp\/v2\/posts?tags=573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}